{"id":2512,"date":"2021-01-21T17:11:31","date_gmt":"2021-01-21T16:11:31","guid":{"rendered":"https:\/\/new.xitee.com\/about-us\/"},"modified":"2021-08-19T10:02:25","modified_gmt":"2021-08-19T08:02:25","slug":"o-nas","status":"publish","type":"page","link":"https:\/\/xitee.com\/cs\/o-nas\/","title":{"rendered":"O n\u00e1s"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-2512","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>O n\u00e1s - xitee<\/title>\n<meta name=\"description\" content=\"Xitee je poskytovatel IT slu\u017eeb se s\u00eddlem v Praze. Na\u0161e odborn\u00e9 znalosti se soust\u0159ed\u00ed na sektory digit\u00e1ln\u00edho podnik\u00e1n\u00ed, financ\u00ed a energetiky a zdravotnictv\u00ed. \u2705\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/xitee.com\/cs\/o-nas\/\" \/>\n<meta property=\"og:locale\" content=\"cs_CZ\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O n\u00e1s - xitee\" \/>\n<meta property=\"og:description\" content=\"Xitee je poskytovatel IT slu\u017eeb se s\u00eddlem v Praze. Na\u0161e odborn\u00e9 znalosti se soust\u0159ed\u00ed na sektory digit\u00e1ln\u00edho podnik\u00e1n\u00ed, financ\u00ed a energetiky a zdravotnictv\u00ed. \u2705\" \/>\n<meta property=\"og:url\" content=\"https:\/\/xitee.com\/cs\/o-nas\/\" \/>\n<meta property=\"og:site_name\" content=\"xitee\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-19T08:02:25+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/xitee.com\\\/cs\\\/o-nas\\\/\",\"url\":\"https:\\\/\\\/xitee.com\\\/cs\\\/o-nas\\\/\",\"name\":\"O n\u00e1s - xitee\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/xitee.com\\\/#website\"},\"datePublished\":\"2021-01-21T16:11:31+00:00\",\"dateModified\":\"2021-08-19T08:02:25+00:00\",\"description\":\"Xitee je poskytovatel IT slu\u017eeb se s\u00eddlem v Praze. Na\u0161e odborn\u00e9 znalosti se soust\u0159ed\u00ed na sektory digit\u00e1ln\u00edho podnik\u00e1n\u00ed, financ\u00ed a energetiky a zdravotnictv\u00ed. \u2705\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/xitee.com\\\/cs\\\/o-nas\\\/#breadcrumb\"},\"inLanguage\":\"cs\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/xitee.com\\\/cs\\\/o-nas\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/xitee.com\\\/cs\\\/o-nas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Dom\u016f\",\"item\":\"https:\\\/\\\/xitee.com\\\/cs\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O n\u00e1s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/xitee.com\\\/#website\",\"url\":\"https:\\\/\\\/xitee.com\\\/\",\"name\":\"xitee\",\"description\":\"Poskytovatel IT slu\u017eeb se s\u00eddlem v Praze. Na\u0161e odborn\u00e9 znalosti se soust\u0159ed\u00ed na sektory digit\u00e1ln\u00edho podnik\u00e1n\u00ed, financ\u00ed a energetiky a zdravotnictv\u00ed.\",\"publisher\":{\"@id\":\"https:\\\/\\\/xitee.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/xitee.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"cs\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/xitee.com\\\/#organization\",\"name\":\"xitee\",\"url\":\"https:\\\/\\\/xitee.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"cs\",\"@id\":\"https:\\\/\\\/xitee.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/xitee.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/logo-header.svg\",\"contentUrl\":\"https:\\\/\\\/xitee.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/logo-header.svg\",\"width\":86,\"height\":30,\"caption\":\"xitee\"},\"image\":{\"@id\":\"https:\\\/\\\/xitee.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O n\u00e1s - xitee","description":"Xitee je poskytovatel IT slu\u017eeb se s\u00eddlem v Praze. Na\u0161e odborn\u00e9 znalosti se soust\u0159ed\u00ed na sektory digit\u00e1ln\u00edho podnik\u00e1n\u00ed, financ\u00ed a energetiky a zdravotnictv\u00ed. \u2705","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/xitee.com\/cs\/o-nas\/","og_locale":"cs_CZ","og_type":"article","og_title":"O n\u00e1s - xitee","og_description":"Xitee je poskytovatel IT slu\u017eeb se s\u00eddlem v Praze. Na\u0161e odborn\u00e9 znalosti se soust\u0159ed\u00ed na sektory digit\u00e1ln\u00edho podnik\u00e1n\u00ed, financ\u00ed a energetiky a zdravotnictv\u00ed. \u2705","og_url":"https:\/\/xitee.com\/cs\/o-nas\/","og_site_name":"xitee","article_modified_time":"2021-08-19T08:02:25+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/xitee.com\/cs\/o-nas\/","url":"https:\/\/xitee.com\/cs\/o-nas\/","name":"O n\u00e1s - xitee","isPartOf":{"@id":"https:\/\/xitee.com\/#website"},"datePublished":"2021-01-21T16:11:31+00:00","dateModified":"2021-08-19T08:02:25+00:00","description":"Xitee je poskytovatel IT slu\u017eeb se s\u00eddlem v Praze. Na\u0161e odborn\u00e9 znalosti se soust\u0159ed\u00ed na sektory digit\u00e1ln\u00edho podnik\u00e1n\u00ed, financ\u00ed a energetiky a zdravotnictv\u00ed. \u2705","breadcrumb":{"@id":"https:\/\/xitee.com\/cs\/o-nas\/#breadcrumb"},"inLanguage":"cs","potentialAction":[{"@type":"ReadAction","target":["https:\/\/xitee.com\/cs\/o-nas\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/xitee.com\/cs\/o-nas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Dom\u016f","item":"https:\/\/xitee.com\/cs\/"},{"@type":"ListItem","position":2,"name":"O n\u00e1s"}]},{"@type":"WebSite","@id":"https:\/\/xitee.com\/#website","url":"https:\/\/xitee.com\/","name":"xitee","description":"Poskytovatel IT slu\u017eeb se s\u00eddlem v Praze. Na\u0161e odborn\u00e9 znalosti se soust\u0159ed\u00ed na sektory digit\u00e1ln\u00edho podnik\u00e1n\u00ed, financ\u00ed a energetiky a zdravotnictv\u00ed.","publisher":{"@id":"https:\/\/xitee.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/xitee.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"cs"},{"@type":"Organization","@id":"https:\/\/xitee.com\/#organization","name":"xitee","url":"https:\/\/xitee.com\/","logo":{"@type":"ImageObject","inLanguage":"cs","@id":"https:\/\/xitee.com\/#\/schema\/logo\/image\/","url":"https:\/\/xitee.com\/wp-content\/uploads\/2021\/03\/logo-header.svg","contentUrl":"https:\/\/xitee.com\/wp-content\/uploads\/2021\/03\/logo-header.svg","width":86,"height":30,"caption":"xitee"},"image":{"@id":"https:\/\/xitee.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/xitee.com\/cs\/wp-json\/wp\/v2\/pages\/2512","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xitee.com\/cs\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/xitee.com\/cs\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/xitee.com\/cs\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/xitee.com\/cs\/wp-json\/wp\/v2\/comments?post=2512"}],"version-history":[{"count":1,"href":"https:\/\/xitee.com\/cs\/wp-json\/wp\/v2\/pages\/2512\/revisions"}],"predecessor-version":[{"id":3049,"href":"https:\/\/xitee.com\/cs\/wp-json\/wp\/v2\/pages\/2512\/revisions\/3049"}],"wp:attachment":[{"href":"https:\/\/xitee.com\/cs\/wp-json\/wp\/v2\/media?parent=2512"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}