{"id":2408,"date":"2021-02-24T14:19:41","date_gmt":"2021-02-24T13:19:41","guid":{"rendered":"https:\/\/new.xitee.com\/industry\/digital-businesses\/"},"modified":"2021-09-06T12:28:06","modified_gmt":"2021-09-06T10:28:06","slug":"digitale-unternehmen","status":"publish","type":"industry","link":"https:\/\/xitee.com\/de\/industry\/digitale-unternehmen\/","title":{"rendered":"Digitale Unternehmen"},"excerpt":{"rendered":"<p>Wir begleiten unsere Kunden durch den Prozess der digitalen Transformation, welcher es ihnen erm\u00f6glicht, die Kraft skalierbarer Technologien zu nutzen und ihr Gesch\u00e4ft auszubauen.<\/p>\n","protected":false},"featured_media":2409,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"services_category":[190,192,194,196,198,200],"class_list":["post-2408","industry","type-industry","status-publish","has-post-thumbnail","hentry","services_category-cloudification-de","services_category-data-protection-security-de","services_category-it-consulting-and-expert-services-de","services_category-software-development-de","services_category-software-testing-de","services_category-verwaltete-it-dienste"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Digitale Unternehmen | xitee<\/title>\n<meta name=\"description\" content=\"Zusammen mit unserem Partner HBSN AG bieten wir unseren Kunden komplexe Dienstleistungen aus der Digital Bussiness-Industrie in hoher Qualit\u00e4t.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/xitee.com\/de\/industry\/digitale-unternehmen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Digitale Unternehmen | xitee\" \/>\n<meta property=\"og:description\" content=\"Zusammen mit unserem Partner HBSN AG bieten wir unseren Kunden komplexe Dienstleistungen aus der Digital Bussiness-Industrie in hoher Qualit\u00e4t.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/xitee.com\/de\/industry\/digitale-unternehmen\/\" \/>\n<meta property=\"og:site_name\" content=\"xitee\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-06T10:28:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/xitee.com\/wp-content\/uploads\/2021\/02\/Asset-2@2x-100-Copy@2x1-min.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1467\" \/>\n\t<meta property=\"og:image:height\" content=\"1072\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/xitee.com\\\/de\\\/industry\\\/digitale-unternehmen\\\/\",\"url\":\"https:\\\/\\\/xitee.com\\\/de\\\/industry\\\/digitale-unternehmen\\\/\",\"name\":\"Digitale Unternehmen | xitee\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/xitee.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/xitee.com\\\/de\\\/industry\\\/digitale-unternehmen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/xitee.com\\\/de\\\/industry\\\/digitale-unternehmen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/xitee.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Asset-2@2x-100-Copy@2x1-min.jpeg\",\"datePublished\":\"2021-02-24T13:19:41+00:00\",\"dateModified\":\"2021-09-06T10:28:06+00:00\",\"description\":\"Zusammen mit unserem Partner HBSN AG bieten wir unseren Kunden komplexe Dienstleistungen aus der Digital Bussiness-Industrie in hoher Qualit\u00e4t.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/xitee.com\\\/de\\\/industry\\\/digitale-unternehmen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/xitee.com\\\/de\\\/industry\\\/digitale-unternehmen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/xitee.com\\\/de\\\/industry\\\/digitale-unternehmen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/xitee.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Asset-2@2x-100-Copy@2x1-min.jpeg\",\"contentUrl\":\"https:\\\/\\\/xitee.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Asset-2@2x-100-Copy@2x1-min.jpeg\",\"width\":1467,\"height\":1072},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/xitee.com\\\/de\\\/industry\\\/digitale-unternehmen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Dom\u016f\",\"item\":\"https:\\\/\\\/xitee.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Digitale Unternehmen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/xitee.com\\\/#website\",\"url\":\"https:\\\/\\\/xitee.com\\\/\",\"name\":\"xitee\",\"description\":\"IT-Dienstleister mit Sitz in Prag, Tschechische Republik. Unsere Expertise liegt in den Sektoren f\u00fcr Digitale Unternehmen, Finanzen &amp; Energie sowie Gesundheitswesen.\",\"publisher\":{\"@id\":\"https:\\\/\\\/xitee.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/xitee.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/xitee.com\\\/#organization\",\"name\":\"xitee\",\"url\":\"https:\\\/\\\/xitee.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/xitee.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/xitee.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/logo-header.svg\",\"contentUrl\":\"https:\\\/\\\/xitee.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/logo-header.svg\",\"width\":86,\"height\":30,\"caption\":\"xitee\"},\"image\":{\"@id\":\"https:\\\/\\\/xitee.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Digitale Unternehmen | xitee","description":"Zusammen mit unserem Partner HBSN AG bieten wir unseren Kunden komplexe Dienstleistungen aus der Digital Bussiness-Industrie in hoher Qualit\u00e4t.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/xitee.com\/de\/industry\/digitale-unternehmen\/","og_locale":"de_DE","og_type":"article","og_title":"Digitale Unternehmen | xitee","og_description":"Zusammen mit unserem Partner HBSN AG bieten wir unseren Kunden komplexe Dienstleistungen aus der Digital Bussiness-Industrie in hoher Qualit\u00e4t.","og_url":"https:\/\/xitee.com\/de\/industry\/digitale-unternehmen\/","og_site_name":"xitee","article_modified_time":"2021-09-06T10:28:06+00:00","og_image":[{"width":1467,"height":1072,"url":"https:\/\/xitee.com\/wp-content\/uploads\/2021\/02\/Asset-2@2x-100-Copy@2x1-min.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/xitee.com\/de\/industry\/digitale-unternehmen\/","url":"https:\/\/xitee.com\/de\/industry\/digitale-unternehmen\/","name":"Digitale Unternehmen | xitee","isPartOf":{"@id":"https:\/\/xitee.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/xitee.com\/de\/industry\/digitale-unternehmen\/#primaryimage"},"image":{"@id":"https:\/\/xitee.com\/de\/industry\/digitale-unternehmen\/#primaryimage"},"thumbnailUrl":"https:\/\/xitee.com\/wp-content\/uploads\/2021\/02\/Asset-2@2x-100-Copy@2x1-min.jpeg","datePublished":"2021-02-24T13:19:41+00:00","dateModified":"2021-09-06T10:28:06+00:00","description":"Zusammen mit unserem Partner HBSN AG bieten wir unseren Kunden komplexe Dienstleistungen aus der Digital Bussiness-Industrie in hoher Qualit\u00e4t.","breadcrumb":{"@id":"https:\/\/xitee.com\/de\/industry\/digitale-unternehmen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/xitee.com\/de\/industry\/digitale-unternehmen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/xitee.com\/de\/industry\/digitale-unternehmen\/#primaryimage","url":"https:\/\/xitee.com\/wp-content\/uploads\/2021\/02\/Asset-2@2x-100-Copy@2x1-min.jpeg","contentUrl":"https:\/\/xitee.com\/wp-content\/uploads\/2021\/02\/Asset-2@2x-100-Copy@2x1-min.jpeg","width":1467,"height":1072},{"@type":"BreadcrumbList","@id":"https:\/\/xitee.com\/de\/industry\/digitale-unternehmen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Dom\u016f","item":"https:\/\/xitee.com\/de\/"},{"@type":"ListItem","position":2,"name":"Digitale Unternehmen"}]},{"@type":"WebSite","@id":"https:\/\/xitee.com\/#website","url":"https:\/\/xitee.com\/","name":"xitee","description":"IT-Dienstleister mit Sitz in Prag, Tschechische Republik. Unsere Expertise liegt in den Sektoren f\u00fcr Digitale Unternehmen, Finanzen &amp; Energie sowie Gesundheitswesen.","publisher":{"@id":"https:\/\/xitee.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/xitee.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/xitee.com\/#organization","name":"xitee","url":"https:\/\/xitee.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/xitee.com\/#\/schema\/logo\/image\/","url":"https:\/\/xitee.com\/wp-content\/uploads\/2021\/03\/logo-header.svg","contentUrl":"https:\/\/xitee.com\/wp-content\/uploads\/2021\/03\/logo-header.svg","width":86,"height":30,"caption":"xitee"},"image":{"@id":"https:\/\/xitee.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/xitee.com\/de\/wp-json\/wp\/v2\/industry\/2408","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xitee.com\/de\/wp-json\/wp\/v2\/industry"}],"about":[{"href":"https:\/\/xitee.com\/de\/wp-json\/wp\/v2\/types\/industry"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/xitee.com\/de\/wp-json\/wp\/v2\/media\/2409"}],"wp:attachment":[{"href":"https:\/\/xitee.com\/de\/wp-json\/wp\/v2\/media?parent=2408"}],"wp:term":[{"taxonomy":"services_category","embeddable":true,"href":"https:\/\/xitee.com\/de\/wp-json\/wp\/v2\/services_category?post=2408"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}