{"id":2520,"date":"2021-01-28T00:17:56","date_gmt":"2021-01-27T23:17:56","guid":{"rendered":"https:\/\/new.xitee.com\/about-us\/about-team\/"},"modified":"2025-08-22T15:36:44","modified_gmt":"2025-08-22T13:36:44","slug":"about-team","status":"publish","type":"page","link":"https:\/\/xitee.com\/de\/about-us\/about-team\/","title":{"rendered":"Das sind wir"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":4539,"parent":2513,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"rn_about_team.php","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-2520","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>About Team | xitee<\/title>\n<meta name=\"description\" content=\"Wir sind uns bewusst, dass unsere Mitarbeiter die wichtigsten Komponente sind, daher f\u00f6rdern wir aktiv ihre pers\u00f6nliche Entwicklung. \u2705\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/xitee.com\/de\/about-us\/about-team\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"About Team | xitee\" \/>\n<meta property=\"og:description\" content=\"Wir sind uns bewusst, dass unsere Mitarbeiter die wichtigsten Komponente sind, daher f\u00f6rdern wir aktiv ihre pers\u00f6nliche Entwicklung. \u2705\" \/>\n<meta property=\"og:url\" content=\"https:\/\/xitee.com\/de\/about-us\/about-team\/\" \/>\n<meta property=\"og:site_name\" content=\"xitee\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-22T13:36:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/xitee.com\/wp-content\/uploads\/2021\/09\/interier-31-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1372\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/xitee.com\\\/de\\\/about-us\\\/about-team\\\/\",\"url\":\"https:\\\/\\\/xitee.com\\\/de\\\/about-us\\\/about-team\\\/\",\"name\":\"About Team | xitee\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/xitee.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/xitee.com\\\/de\\\/about-us\\\/about-team\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/xitee.com\\\/de\\\/about-us\\\/about-team\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/xitee.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/interier-31-scaled.jpg\",\"datePublished\":\"2021-01-27T23:17:56+00:00\",\"dateModified\":\"2025-08-22T13:36:44+00:00\",\"description\":\"Wir sind uns bewusst, dass unsere Mitarbeiter die wichtigsten Komponente sind, daher f\u00f6rdern wir aktiv ihre pers\u00f6nliche Entwicklung. \u2705\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/xitee.com\\\/de\\\/about-us\\\/about-team\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/xitee.com\\\/de\\\/about-us\\\/about-team\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/xitee.com\\\/de\\\/about-us\\\/about-team\\\/#primaryimage\",\"url\":\"https:\\\/\\\/xitee.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/interier-31-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/xitee.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/interier-31-scaled.jpg\",\"width\":2560,\"height\":1372},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/xitee.com\\\/de\\\/about-us\\\/about-team\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Dom\u016f\",\"item\":\"https:\\\/\\\/xitee.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"About Us\",\"item\":\"https:\\\/\\\/xitee.com\\\/de\\\/about-us\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Das sind wir\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/xitee.com\\\/#website\",\"url\":\"https:\\\/\\\/xitee.com\\\/\",\"name\":\"xitee\",\"description\":\"IT-Dienstleister mit Sitz in Prag, Tschechische Republik. Unsere Expertise liegt in den Sektoren f\u00fcr Digitale Unternehmen, Finanzen &amp; Energie sowie Gesundheitswesen.\",\"publisher\":{\"@id\":\"https:\\\/\\\/xitee.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/xitee.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/xitee.com\\\/#organization\",\"name\":\"xitee\",\"url\":\"https:\\\/\\\/xitee.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/xitee.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/xitee.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/logo-header.svg\",\"contentUrl\":\"https:\\\/\\\/xitee.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/logo-header.svg\",\"width\":86,\"height\":30,\"caption\":\"xitee\"},\"image\":{\"@id\":\"https:\\\/\\\/xitee.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"About Team | xitee","description":"Wir sind uns bewusst, dass unsere Mitarbeiter die wichtigsten Komponente sind, daher f\u00f6rdern wir aktiv ihre pers\u00f6nliche Entwicklung. \u2705","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/xitee.com\/de\/about-us\/about-team\/","og_locale":"de_DE","og_type":"article","og_title":"About Team | xitee","og_description":"Wir sind uns bewusst, dass unsere Mitarbeiter die wichtigsten Komponente sind, daher f\u00f6rdern wir aktiv ihre pers\u00f6nliche Entwicklung. \u2705","og_url":"https:\/\/xitee.com\/de\/about-us\/about-team\/","og_site_name":"xitee","article_modified_time":"2025-08-22T13:36:44+00:00","og_image":[{"width":2560,"height":1372,"url":"https:\/\/xitee.com\/wp-content\/uploads\/2021\/09\/interier-31-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/xitee.com\/de\/about-us\/about-team\/","url":"https:\/\/xitee.com\/de\/about-us\/about-team\/","name":"About Team | xitee","isPartOf":{"@id":"https:\/\/xitee.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/xitee.com\/de\/about-us\/about-team\/#primaryimage"},"image":{"@id":"https:\/\/xitee.com\/de\/about-us\/about-team\/#primaryimage"},"thumbnailUrl":"https:\/\/xitee.com\/wp-content\/uploads\/2021\/09\/interier-31-scaled.jpg","datePublished":"2021-01-27T23:17:56+00:00","dateModified":"2025-08-22T13:36:44+00:00","description":"Wir sind uns bewusst, dass unsere Mitarbeiter die wichtigsten Komponente sind, daher f\u00f6rdern wir aktiv ihre pers\u00f6nliche Entwicklung. \u2705","breadcrumb":{"@id":"https:\/\/xitee.com\/de\/about-us\/about-team\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/xitee.com\/de\/about-us\/about-team\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/xitee.com\/de\/about-us\/about-team\/#primaryimage","url":"https:\/\/xitee.com\/wp-content\/uploads\/2021\/09\/interier-31-scaled.jpg","contentUrl":"https:\/\/xitee.com\/wp-content\/uploads\/2021\/09\/interier-31-scaled.jpg","width":2560,"height":1372},{"@type":"BreadcrumbList","@id":"https:\/\/xitee.com\/de\/about-us\/about-team\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Dom\u016f","item":"https:\/\/xitee.com\/de\/"},{"@type":"ListItem","position":2,"name":"About Us","item":"https:\/\/xitee.com\/de\/about-us\/"},{"@type":"ListItem","position":3,"name":"Das sind wir"}]},{"@type":"WebSite","@id":"https:\/\/xitee.com\/#website","url":"https:\/\/xitee.com\/","name":"xitee","description":"IT-Dienstleister mit Sitz in Prag, Tschechische Republik. Unsere Expertise liegt in den Sektoren f\u00fcr Digitale Unternehmen, Finanzen &amp; Energie sowie Gesundheitswesen.","publisher":{"@id":"https:\/\/xitee.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/xitee.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/xitee.com\/#organization","name":"xitee","url":"https:\/\/xitee.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/xitee.com\/#\/schema\/logo\/image\/","url":"https:\/\/xitee.com\/wp-content\/uploads\/2021\/03\/logo-header.svg","contentUrl":"https:\/\/xitee.com\/wp-content\/uploads\/2021\/03\/logo-header.svg","width":86,"height":30,"caption":"xitee"},"image":{"@id":"https:\/\/xitee.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/xitee.com\/de\/wp-json\/wp\/v2\/pages\/2520","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xitee.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/xitee.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/xitee.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/xitee.com\/de\/wp-json\/wp\/v2\/comments?post=2520"}],"version-history":[{"count":15,"href":"https:\/\/xitee.com\/de\/wp-json\/wp\/v2\/pages\/2520\/revisions"}],"predecessor-version":[{"id":5236,"href":"https:\/\/xitee.com\/de\/wp-json\/wp\/v2\/pages\/2520\/revisions\/5236"}],"up":[{"embeddable":true,"href":"https:\/\/xitee.com\/de\/wp-json\/wp\/v2\/pages\/2513"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/xitee.com\/de\/wp-json\/wp\/v2\/media\/4539"}],"wp:attachment":[{"href":"https:\/\/xitee.com\/de\/wp-json\/wp\/v2\/media?parent=2520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}