{"id":3896,"date":"2021-06-18T13:47:45","date_gmt":"2021-06-18T11:47:45","guid":{"rendered":"https:\/\/new.xitee.com\/?post_type=projects&#038;p=3896"},"modified":"2021-08-16T11:23:58","modified_gmt":"2021-08-16T09:23:58","slug":"system-fuer-terminplanung-korrespondenz-und-digitale-uebertragung-von-berichten","status":"publish","type":"projects","link":"https:\/\/xitee.com\/de\/projects\/system-fuer-terminplanung-korrespondenz-und-digitale-uebertragung-von-berichten\/","title":{"rendered":"System f\u00fcr Terminplanung, Korrespondenz und digitale \u00dcbertragung von Berichten"},"content":{"rendered":"\n<p><a href=\"https:\/\/www.medicproof.de\/\" target=\"_blank\" rel=\"noreferrer noopener\">Medicproof<\/a> ist eine Tochtergesellschaft eines unserer Hauptkunden &#8211; PKV. Medicproof bietet eine Beurteilung von Versicherungsf\u00e4llen f\u00fcr Personen, die unter einer der privaten Versicherungsgesellschaften versichert sind. Medicproof garantiert, dass alle Bewertungen gem\u00e4\u00df den Gesetzen und Vorschriften durchgef\u00fchrt werden und unter Einhaltung der gleichen Standards in allen F\u00e4llen durchgef\u00fchrt werden.<\/p>\n\n\n\n<p>Um ihre Arbeit zu rationalisieren, werden viele Systeme von den Mitarbeitern und Assessment-Experten eingesetzt. Eine der Kernapplikationen ist ProofCenter, das System, das unser Team bei der Entwicklung und Wartung unterst\u00fctzte. <\/p>\n\n\n\n<p>In dieser Applikation werden alle Bewertungen von medizinischen Experten verwaltet. ProofCenter wird direkt oder indirekt von allen anderen Systemen im MEDICPROOF-\u00d6kosystem verwendet. Die Applikation besteht aus Backend und Frontend (ProofCenter Client).<\/p>\n\n\n\n<p>Technologien: Intellij IDEA; SQL Management Studio, JBoss \/ Java, EJB, Spring, JAVA EE, Hibernate, REST, Git<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Medicproof ist eine Tochtergesellschaft eines unserer Hauptkunden &#8211; PKV. Medicproof bietet eine Beurteilung von Versicherungsf\u00e4llen f\u00fcr Personen, die unter einer der privaten Versicherungsgesellschaften versichert sind. Medicproof garantiert, dass alle Bewertungen gem\u00e4\u00df den Gesetzen und Vorschriften durchgef\u00fchrt werden und unter Einhaltung der gleichen Standards in allen F\u00e4llen durchgef\u00fchrt werden. Um ihre Arbeit zu rationalisieren, werden viele [&hellip;]<\/p>\n","protected":false},"featured_media":3029,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"tags":[234],"industry_category":[152],"country":[206],"technology":[164],"services_category":[194,196,198,200],"class_list":["post-3896","projects","type-projects","status-publish","has-post-thumbnail","hentry","tag-krankenversicherung","industry_category-healthcare-de","country-germany-de","technology-java-de","services_category-it-consulting-and-expert-services-de","services_category-software-development-de","services_category-software-testing-de","services_category-verwaltete-it-dienste"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>System f\u00fcr Terminplanung, Korrespondenz und digitale \u00dcbertragung von Berichten - xitee<\/title>\n<meta name=\"description\" content=\"Um ihre Arbeit zu rationalisieren, werden viele Systeme von den Mitarbeitern eingesetzt. Eine der Kernapplikationen ist ProofCenter, das wir bei der Entwicklung und Wartung unterst\u00fctzte.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/xitee.com\/de\/projects\/system-fuer-terminplanung-korrespondenz-und-digitale-uebertragung-von-berichten\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"System f\u00fcr Terminplanung, Korrespondenz und digitale \u00dcbertragung von Berichten - xitee\" \/>\n<meta property=\"og:description\" content=\"Um ihre Arbeit zu rationalisieren, werden viele Systeme von den Mitarbeitern eingesetzt. Eine der Kernapplikationen ist ProofCenter, das wir bei der Entwicklung und Wartung unterst\u00fctzte.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/xitee.com\/de\/projects\/system-fuer-terminplanung-korrespondenz-und-digitale-uebertragung-von-berichten\/\" \/>\n<meta property=\"og:site_name\" content=\"xitee\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-16T09:23:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/xitee.com\/wp-content\/uploads\/2021\/02\/ind-1-1-min.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1466\" \/>\n\t<meta property=\"og:image:height\" content=\"1070\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/xitee.com\\\/de\\\/projects\\\/system-fuer-terminplanung-korrespondenz-und-digitale-uebertragung-von-berichten\\\/\",\"url\":\"https:\\\/\\\/xitee.com\\\/de\\\/projects\\\/system-fuer-terminplanung-korrespondenz-und-digitale-uebertragung-von-berichten\\\/\",\"name\":\"System f\u00fcr Terminplanung, Korrespondenz und digitale \u00dcbertragung von Berichten - xitee\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/xitee.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/xitee.com\\\/de\\\/projects\\\/system-fuer-terminplanung-korrespondenz-und-digitale-uebertragung-von-berichten\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/xitee.com\\\/de\\\/projects\\\/system-fuer-terminplanung-korrespondenz-und-digitale-uebertragung-von-berichten\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/xitee.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/ind-1-1-min.jpg\",\"datePublished\":\"2021-06-18T11:47:45+00:00\",\"dateModified\":\"2021-08-16T09:23:58+00:00\",\"description\":\"Um ihre Arbeit zu rationalisieren, werden viele Systeme von den Mitarbeitern eingesetzt. Eine der Kernapplikationen ist ProofCenter, das wir bei der Entwicklung und Wartung unterst\u00fctzte.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/xitee.com\\\/de\\\/projects\\\/system-fuer-terminplanung-korrespondenz-und-digitale-uebertragung-von-berichten\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/xitee.com\\\/de\\\/projects\\\/system-fuer-terminplanung-korrespondenz-und-digitale-uebertragung-von-berichten\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/xitee.com\\\/de\\\/projects\\\/system-fuer-terminplanung-korrespondenz-und-digitale-uebertragung-von-berichten\\\/#primaryimage\",\"url\":\"https:\\\/\\\/xitee.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/ind-1-1-min.jpg\",\"contentUrl\":\"https:\\\/\\\/xitee.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/ind-1-1-min.jpg\",\"width\":1466,\"height\":1070},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/xitee.com\\\/de\\\/projects\\\/system-fuer-terminplanung-korrespondenz-und-digitale-uebertragung-von-berichten\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Dom\u016f\",\"item\":\"https:\\\/\\\/xitee.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"System f\u00fcr Terminplanung, Korrespondenz und digitale \u00dcbertragung von Berichten\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/xitee.com\\\/#website\",\"url\":\"https:\\\/\\\/xitee.com\\\/\",\"name\":\"xitee\",\"description\":\"IT-Dienstleister mit Sitz in Prag, Tschechische Republik. Unsere Expertise liegt in den Sektoren f\u00fcr Digitale Unternehmen, Finanzen &amp; Energie sowie Gesundheitswesen.\",\"publisher\":{\"@id\":\"https:\\\/\\\/xitee.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/xitee.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/xitee.com\\\/#organization\",\"name\":\"xitee\",\"url\":\"https:\\\/\\\/xitee.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/xitee.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/xitee.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/logo-header.svg\",\"contentUrl\":\"https:\\\/\\\/xitee.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/logo-header.svg\",\"width\":86,\"height\":30,\"caption\":\"xitee\"},\"image\":{\"@id\":\"https:\\\/\\\/xitee.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"System f\u00fcr Terminplanung, Korrespondenz und digitale \u00dcbertragung von Berichten - xitee","description":"Um ihre Arbeit zu rationalisieren, werden viele Systeme von den Mitarbeitern eingesetzt. Eine der Kernapplikationen ist ProofCenter, das wir bei der Entwicklung und Wartung unterst\u00fctzte.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/xitee.com\/de\/projects\/system-fuer-terminplanung-korrespondenz-und-digitale-uebertragung-von-berichten\/","og_locale":"de_DE","og_type":"article","og_title":"System f\u00fcr Terminplanung, Korrespondenz und digitale \u00dcbertragung von Berichten - xitee","og_description":"Um ihre Arbeit zu rationalisieren, werden viele Systeme von den Mitarbeitern eingesetzt. Eine der Kernapplikationen ist ProofCenter, das wir bei der Entwicklung und Wartung unterst\u00fctzte.","og_url":"https:\/\/xitee.com\/de\/projects\/system-fuer-terminplanung-korrespondenz-und-digitale-uebertragung-von-berichten\/","og_site_name":"xitee","article_modified_time":"2021-08-16T09:23:58+00:00","og_image":[{"width":1466,"height":1070,"url":"https:\/\/xitee.com\/wp-content\/uploads\/2021\/02\/ind-1-1-min.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/xitee.com\/de\/projects\/system-fuer-terminplanung-korrespondenz-und-digitale-uebertragung-von-berichten\/","url":"https:\/\/xitee.com\/de\/projects\/system-fuer-terminplanung-korrespondenz-und-digitale-uebertragung-von-berichten\/","name":"System f\u00fcr Terminplanung, Korrespondenz und digitale \u00dcbertragung von Berichten - xitee","isPartOf":{"@id":"https:\/\/xitee.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/xitee.com\/de\/projects\/system-fuer-terminplanung-korrespondenz-und-digitale-uebertragung-von-berichten\/#primaryimage"},"image":{"@id":"https:\/\/xitee.com\/de\/projects\/system-fuer-terminplanung-korrespondenz-und-digitale-uebertragung-von-berichten\/#primaryimage"},"thumbnailUrl":"https:\/\/xitee.com\/wp-content\/uploads\/2021\/02\/ind-1-1-min.jpg","datePublished":"2021-06-18T11:47:45+00:00","dateModified":"2021-08-16T09:23:58+00:00","description":"Um ihre Arbeit zu rationalisieren, werden viele Systeme von den Mitarbeitern eingesetzt. Eine der Kernapplikationen ist ProofCenter, das wir bei der Entwicklung und Wartung unterst\u00fctzte.","breadcrumb":{"@id":"https:\/\/xitee.com\/de\/projects\/system-fuer-terminplanung-korrespondenz-und-digitale-uebertragung-von-berichten\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/xitee.com\/de\/projects\/system-fuer-terminplanung-korrespondenz-und-digitale-uebertragung-von-berichten\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/xitee.com\/de\/projects\/system-fuer-terminplanung-korrespondenz-und-digitale-uebertragung-von-berichten\/#primaryimage","url":"https:\/\/xitee.com\/wp-content\/uploads\/2021\/02\/ind-1-1-min.jpg","contentUrl":"https:\/\/xitee.com\/wp-content\/uploads\/2021\/02\/ind-1-1-min.jpg","width":1466,"height":1070},{"@type":"BreadcrumbList","@id":"https:\/\/xitee.com\/de\/projects\/system-fuer-terminplanung-korrespondenz-und-digitale-uebertragung-von-berichten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Dom\u016f","item":"https:\/\/xitee.com\/de\/"},{"@type":"ListItem","position":2,"name":"System f\u00fcr Terminplanung, Korrespondenz und digitale \u00dcbertragung von Berichten"}]},{"@type":"WebSite","@id":"https:\/\/xitee.com\/#website","url":"https:\/\/xitee.com\/","name":"xitee","description":"IT-Dienstleister mit Sitz in Prag, Tschechische Republik. Unsere Expertise liegt in den Sektoren f\u00fcr Digitale Unternehmen, Finanzen &amp; Energie sowie Gesundheitswesen.","publisher":{"@id":"https:\/\/xitee.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/xitee.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/xitee.com\/#organization","name":"xitee","url":"https:\/\/xitee.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/xitee.com\/#\/schema\/logo\/image\/","url":"https:\/\/xitee.com\/wp-content\/uploads\/2021\/03\/logo-header.svg","contentUrl":"https:\/\/xitee.com\/wp-content\/uploads\/2021\/03\/logo-header.svg","width":86,"height":30,"caption":"xitee"},"image":{"@id":"https:\/\/xitee.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/xitee.com\/de\/wp-json\/wp\/v2\/projects\/3896","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xitee.com\/de\/wp-json\/wp\/v2\/projects"}],"about":[{"href":"https:\/\/xitee.com\/de\/wp-json\/wp\/v2\/types\/projects"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/xitee.com\/de\/wp-json\/wp\/v2\/media\/3029"}],"wp:attachment":[{"href":"https:\/\/xitee.com\/de\/wp-json\/wp\/v2\/media?parent=3896"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/xitee.com\/de\/wp-json\/wp\/v2\/tags?post=3896"},{"taxonomy":"industry_category","embeddable":true,"href":"https:\/\/xitee.com\/de\/wp-json\/wp\/v2\/industry_category?post=3896"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/xitee.com\/de\/wp-json\/wp\/v2\/country?post=3896"},{"taxonomy":"technology","embeddable":true,"href":"https:\/\/xitee.com\/de\/wp-json\/wp\/v2\/technology?post=3896"},{"taxonomy":"services_category","embeddable":true,"href":"https:\/\/xitee.com\/de\/wp-json\/wp\/v2\/services_category?post=3896"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}